{"id":5095,"count":1,"description":"","link":"https:\/\/publimar.mx\/index.php\/tag\/bandera-nacional\/","name":"Bandera Nacional","slug":"bandera-nacional","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bandera Nacional archivos - PubliMar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/publimar.mx\/index.php\/tag\/bandera-nacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bandera Nacional archivos - PubliMar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/publimar.mx\/index.php\/tag\/bandera-nacional\/\" \/>\n<meta property=\"og:site_name\" content=\"PubliMar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/publimar.mx\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png\",\"contentUrl\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png\",\"width\":454,\"height\":108,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/publimar.mx\/#personlogo\"},\"sameAs\":[\"https:\/\/publimar.mx\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/publimar.mx\/#website\",\"url\":\"https:\/\/publimar.mx\/\",\"name\":\"PubliMar\",\"description\":\"Informaci\\u00f3n de la Costa Oaxaque\\u00f1a\",\"publisher\":{\"@id\":\"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/publimar.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/publimar.mx\/index.php\/tag\/bandera-nacional\/#webpage\",\"url\":\"https:\/\/publimar.mx\/index.php\/tag\/bandera-nacional\/\",\"name\":\"Bandera Nacional archivos - PubliMar\",\"isPartOf\":{\"@id\":\"https:\/\/publimar.mx\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/tag\/bandera-nacional\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/publimar.mx\/index.php\/tag\/bandera-nacional\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/publimar.mx\/index.php\/tag\/bandera-nacional\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/publimar.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bandera Nacional\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bandera Nacional archivos - PubliMar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/publimar.mx\/index.php\/tag\/bandera-nacional\/","og_locale":"es_ES","og_type":"article","og_title":"Bandera Nacional archivos - PubliMar","og_url":"https:\/\/publimar.mx\/index.php\/tag\/bandera-nacional\/","og_site_name":"PubliMar","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Person","Organization"],"@id":"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/publimar.mx\/#personlogo","inLanguage":"es","url":"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png","contentUrl":"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png","width":454,"height":108,"caption":"admin"},"logo":{"@id":"https:\/\/publimar.mx\/#personlogo"},"sameAs":["https:\/\/publimar.mx"]},{"@type":"WebSite","@id":"https:\/\/publimar.mx\/#website","url":"https:\/\/publimar.mx\/","name":"PubliMar","description":"Informaci\u00f3n de la Costa Oaxaque\u00f1a","publisher":{"@id":"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/publimar.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"CollectionPage","@id":"https:\/\/publimar.mx\/index.php\/tag\/bandera-nacional\/#webpage","url":"https:\/\/publimar.mx\/index.php\/tag\/bandera-nacional\/","name":"Bandera Nacional archivos - PubliMar","isPartOf":{"@id":"https:\/\/publimar.mx\/#website"},"breadcrumb":{"@id":"https:\/\/publimar.mx\/index.php\/tag\/bandera-nacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/publimar.mx\/index.php\/tag\/bandera-nacional\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/publimar.mx\/index.php\/tag\/bandera-nacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/publimar.mx\/"},{"@type":"ListItem","position":2,"name":"Bandera Nacional"}]}]}},"_links":{"self":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/tags\/5095"}],"collection":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/posts?tags=5095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}