{"id":6081,"date":"2023-02-14T18:46:03","date_gmt":"2023-02-15T00:46:03","guid":{"rendered":"https:\/\/publimar.mx\/?p=6081"},"modified":"2023-02-14T18:46:09","modified_gmt":"2023-02-15T00:46:09","slug":"rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco","status":"publish","type":"post","link":"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/","title":{"rendered":"Rinden homenaje a Vicente Guerrero en La Entrega Huatulco"},"content":{"rendered":"\n<ul><li>Playa La Entrega, lugar en el que fue desembarcado el general Guerrero despu\u00e9s de ser traicionado; posteriormente fue trasladado a Cuilapan en donde fue fusilado<\/li><\/ul>\n\n\n\n<p>Ra\u00fal Laguna<\/p>\n\n\n\n<p>LA ENTREGA, HUATULCO. &#8211; El lugar en donde fue entregado por General Francisco Pical\u00faa, la Playa La Entrega fue el escenario de la ceremonia en honor del 192 aniversario luctuoso del general\u00edsimo Vicente Guerrero Salda\u00f1a, quien ha dejado un legado patri\u00f3tico en el estado de Oaxaca.<\/p>\n\n\n\n<p>Autoridades municipales y estatales; as\u00ed como legisladores y mandos militares y marinos se dieron cita en Playa La Entrega para montar una guardia de honor y presentar una corona florar en conmemoraci\u00f3n del 192 aniversario luctuoso del general\u00edsimo Vicente Guerrero, quien fuera traicionado y entregado, precisamente en dicha playa que por el suceso lleva el nombre de \u201cLa Entrega\u201d.<\/p>\n\n\n\n<p>La Entrega, lugar que marc\u00f3 parte de la historia de Guerrero<\/p>\n\n\n\n<p>En la entidad oaxaque\u00f1a cuenta con dos lugares especiales para conmemorar la fecha hist\u00f3rica del 14 de febrero, La Entrega en Santa Mar\u00eda Huatulco y Cuilapan de Guerrero; el primer sitio fue en donde desembarco la nave comandada por Francisco Pical\u00faa, quien despu\u00e9s de una traici\u00f3n en Puerto de Acapulco al general Vicente Guerrero, lo entregara en \u00e9sta playa que actualmente es un destino tur\u00edstico; mientras el segundo sitio, marca el suceso del fusilamiento del segundo Presidente de M\u00e9xico, que hizo patria al luchar por la Independencia nacional.<\/p>\n\n\n\n<p>Para pol\u00edticos como el edil de Santa Mar\u00eda Huatulco, \u201cel legado que nos ha dejado el general\u00edsimo Vicente Guerrero, es delos legados m\u00e1s importantes de la historia y de los personajes que han dado libertad, que han defendido la Patria, que han dado has la vida misma ara que M\u00e9xico fuera independiente, para que M\u00e9xico comenzara a tener la vida que hoy estamos gozando\u201d, coment\u00f3.<\/p>\n\n\n\n<p>Actividades deportivas y socioculturales en La Entrega<\/p>\n\n\n\n<p>En Playa La Entrega, para conmemorar el aniversario luctuoso y celebrar el D\u00eda del amor y la Amistad, los prestadores de servicios y restauranteros, en coordinaci\u00f3n con la autoridad municipal, realizaron diversas actividades deportivas y socioculturales; lo que dio inicio desde las primeras horas del d\u00eda con un torneo de pesca,<\/p>\n\n\n\n<p>Posteriormente al torneo de pesca se realiz\u00f3 el acto c\u00edvico en la que se rindiera el homenaje luctuoso, comenzaron las actividades deportivas como el volibol y futbol playeros; nataci\u00f3n, entre otras.<\/p>\n\n\n\n<p>Por la tarde, la Playa La Entrega se engalan\u00f3 con un baile popular para amenizar y disfrute de los turistas que visitaron el destino tur\u00edstico y locales que saben que tradicionalmente se realizan las actividades sociales, deportivas y culturales.<\/p>\n\n\n\n<p>Rinden homenaje en Santa Mar\u00eda Huatulco<\/p>\n\n\n\n<p>Por la ma\u00f1ana, en la cabecera municipal de Santa Mar\u00eda Huatulco, las autoridades municipales, estatales y efectivos militares, desde la explanada principal conmemoraron en un acto c\u00edvico el 192 aniversario luctuoso del general Vicente Guerrero.<\/p>\n\n\n\n<p>En su estatua, las autoridades presentes rindieron el homenaje y montaron guardia para recordar al general que lucho por la Independencia de M\u00e9xico.<\/p>\n\n\n\n<p>\u201cRecordemos, hoy y siempre, las virtudes, la fortaleza y la valent\u00eda que caracterizaba a este personaje hist\u00f3rico para nuestro pa\u00eds\u201d, coment\u00f3 la autoridad municipal.<\/p>\n\n\n\n<p>Por su parte, efectivos de la Secretar\u00eda de Marina, a trav\u00e9s de la D\u00e9cima Octava Zona Naval realizaron una salva de fusiler\u00eda; mientras tanto, estudiantes del COBAO plantel 22 de Santa Cruz Huatulco realizaron el acompa\u00f1amiento de la Banda de Guerra y el Himno Nacional.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"681\" src=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416696533-1024x681.jpg\" alt=\"\" data-id=\"6082\" data-full-url=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416696533.jpg\" data-link=\"https:\/\/publimar.mx\/?attachment_id=6082\" class=\"wp-image-6082\" srcset=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416696533-1024x681.jpg 1024w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416696533-300x199.jpg 300w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416696533-768x511.jpg 768w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416696533.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"681\" src=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416709610-1024x681.jpg\" alt=\"\" data-id=\"6083\" data-full-url=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416709610.jpg\" data-link=\"https:\/\/publimar.mx\/?attachment_id=6083\" class=\"wp-image-6083\" srcset=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416709610-1024x681.jpg 1024w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416709610-300x199.jpg 300w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416709610-768x511.jpg 768w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416709610.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"681\" src=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416718394-1024x681.jpg\" alt=\"\" data-id=\"6084\" data-full-url=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416718394.jpg\" data-link=\"https:\/\/publimar.mx\/?attachment_id=6084\" class=\"wp-image-6084\" srcset=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416718394-1024x681.jpg 1024w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416718394-300x199.jpg 300w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416718394-768x511.jpg 768w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416718394.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"681\" src=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416706844-1024x681.jpg\" alt=\"\" data-id=\"6085\" data-full-url=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416706844.jpg\" data-link=\"https:\/\/publimar.mx\/?attachment_id=6085\" class=\"wp-image-6085\" srcset=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416706844-1024x681.jpg 1024w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416706844-300x199.jpg 300w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416706844-768x511.jpg 768w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416706844.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416704069-1024x683.jpg\" alt=\"\" data-id=\"6086\" data-full-url=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416704069.jpg\" data-link=\"https:\/\/publimar.mx\/?attachment_id=6086\" class=\"wp-image-6086\" srcset=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416704069-1024x683.jpg 1024w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416704069-300x200.jpg 300w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416704069-768x512.jpg 768w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416704069.jpg 1079w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"681\" src=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416700724-1024x681.jpg\" alt=\"\" data-id=\"6087\" data-full-url=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416700724.jpg\" data-link=\"https:\/\/publimar.mx\/?attachment_id=6087\" class=\"wp-image-6087\" srcset=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416700724-1024x681.jpg 1024w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416700724-300x199.jpg 300w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416700724-768x511.jpg 768w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416700724.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"blob:https:\/\/publimar.mx\/e31f7e7f-6da8-4e42-a549-13efc37a8efb\" data-id=\"\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"blob:https:\/\/publimar.mx\/375aa775-b365-4cb3-b223-60201df47b0a\" data-id=\"\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"blob:https:\/\/publimar.mx\/d631fced-fd34-4cc4-b646-51c02062e1b7\" data-id=\"\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"blob:https:\/\/publimar.mx\/2360da42-96f0-4b45-9169-1959ae0a3fb5\" data-id=\"\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"blob:https:\/\/publimar.mx\/8f837881-6c54-429b-8e62-d9e50d28cb26\" data-id=\"\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img src=\"blob:https:\/\/publimar.mx\/14989383-0add-4c04-a1ea-f445a57823a6\" data-id=\"\"\/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Playa La Entrega, lugar en el que fue desembarcado el general Guerrero despu\u00e9s de ser traicionado; posteriormente fue trasladado a Cuilapan en donde fue fusilado Ra\u00fal Laguna LA ENTREGA, HUATULCO.&hellip; <\/p>\n","protected":false},"author":1,"featured_media":6086,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[4,14],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rinden homenaje a Vicente Guerrero en La Entrega Huatulco - PubliMar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rinden homenaje a Vicente Guerrero en La Entrega Huatulco - PubliMar\" \/>\n<meta property=\"og:description\" content=\"Playa La Entrega, lugar en el que fue desembarcado el general Guerrero despu\u00e9s de ser traicionado; posteriormente fue trasladado a Cuilapan en donde fue fusilado Ra\u00fal Laguna LA ENTREGA, HUATULCO.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/\" \/>\n<meta property=\"og:site_name\" content=\"PubliMar\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-15T00:46:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-15T00:46:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416704069.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1079\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/publimar.mx\/#website\",\"url\":\"https:\/\/publimar.mx\/\",\"name\":\"PubliMar\",\"description\":\"Informaci\\u00f3n de la Costa Oaxaque\\u00f1a\",\"publisher\":{\"@id\":\"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/publimar.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416704069.jpg\",\"contentUrl\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416704069.jpg\",\"width\":1079,\"height\":720},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#webpage\",\"url\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/\",\"name\":\"Rinden homenaje a Vicente Guerrero en La Entrega Huatulco - PubliMar\",\"isPartOf\":{\"@id\":\"https:\/\/publimar.mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#primaryimage\"},\"datePublished\":\"2023-02-15T00:46:03+00:00\",\"dateModified\":\"2023-02-15T00:46:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/publimar.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rinden homenaje a Vicente Guerrero en La Entrega Huatulco\"}]},{\"@type\":[\"Article\",\"NewsArticle\"],\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#webpage\"},\"author\":{\"@id\":\"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558\"},\"headline\":\"Rinden homenaje a Vicente Guerrero en La Entrega Huatulco\",\"datePublished\":\"2023-02-15T00:46:03+00:00\",\"dateModified\":\"2023-02-15T00:46:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#webpage\"},\"wordCount\":602,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558\"},\"image\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416704069.jpg\",\"articleSection\":[\"cultura..\",\"Regional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#respond\"]}]},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/publimar.mx\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png\",\"contentUrl\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png\",\"width\":454,\"height\":108,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/publimar.mx\/#personlogo\"},\"sameAs\":[\"https:\/\/publimar.mx\"],\"url\":\"https:\/\/publimar.mx\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rinden homenaje a Vicente Guerrero en La Entrega Huatulco - PubliMar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/","og_locale":"es_ES","og_type":"article","og_title":"Rinden homenaje a Vicente Guerrero en La Entrega Huatulco - PubliMar","og_description":"Playa La Entrega, lugar en el que fue desembarcado el general Guerrero despu\u00e9s de ser traicionado; posteriormente fue trasladado a Cuilapan en donde fue fusilado Ra\u00fal Laguna LA ENTREGA, HUATULCO.&hellip;","og_url":"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/","og_site_name":"PubliMar","article_published_time":"2023-02-15T00:46:03+00:00","article_modified_time":"2023-02-15T00:46:09+00:00","og_image":[{"width":1079,"height":720,"url":"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416704069.jpg","path":"\/home\/u358712125\/domains\/publimar.mx\/public_html\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416704069.jpg","size":"full","id":6086,"alt":"","pixels":776880,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/publimar.mx\/#website","url":"https:\/\/publimar.mx\/","name":"PubliMar","description":"Informaci\u00f3n de la Costa Oaxaque\u00f1a","publisher":{"@id":"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/publimar.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#primaryimage","inLanguage":"es","url":"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416704069.jpg","contentUrl":"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416704069.jpg","width":1079,"height":720},{"@type":"WebPage","@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#webpage","url":"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/","name":"Rinden homenaje a Vicente Guerrero en La Entrega Huatulco - PubliMar","isPartOf":{"@id":"https:\/\/publimar.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#primaryimage"},"datePublished":"2023-02-15T00:46:03+00:00","dateModified":"2023-02-15T00:46:09+00:00","breadcrumb":{"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/publimar.mx\/"},{"@type":"ListItem","position":2,"name":"Rinden homenaje a Vicente Guerrero en La Entrega Huatulco"}]},{"@type":["Article","NewsArticle"],"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#article","isPartOf":{"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#webpage"},"author":{"@id":"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558"},"headline":"Rinden homenaje a Vicente Guerrero en La Entrega Huatulco","datePublished":"2023-02-15T00:46:03+00:00","dateModified":"2023-02-15T00:46:09+00:00","mainEntityOfPage":{"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#webpage"},"wordCount":602,"commentCount":0,"publisher":{"@id":"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558"},"image":{"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#primaryimage"},"thumbnailUrl":"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/FB_IMG_1676416704069.jpg","articleSection":["cultura..","Regional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/publimar.mx\/index.php\/2023\/02\/14\/rinden-homenaje-a-vicente-guerrero-en-la-entrega-huatulco\/#respond"]}]},{"@type":["Person","Organization"],"@id":"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/publimar.mx\/#personlogo","inLanguage":"es","url":"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png","contentUrl":"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png","width":454,"height":108,"caption":"admin"},"logo":{"@id":"https:\/\/publimar.mx\/#personlogo"},"sameAs":["https:\/\/publimar.mx"],"url":"https:\/\/publimar.mx\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/posts\/6081"}],"collection":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/comments?post=6081"}],"version-history":[{"count":2,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/posts\/6081\/revisions"}],"predecessor-version":[{"id":6090,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/posts\/6081\/revisions\/6090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/media\/6086"}],"wp:attachment":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/media?parent=6081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/categories?post=6081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/tags?post=6081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}