{"id":5978,"date":"2023-02-10T18:25:50","date_gmt":"2023-02-11T00:25:50","guid":{"rendered":"https:\/\/publimar.mx\/?p=5978"},"modified":"2023-02-10T18:25:52","modified_gmt":"2023-02-11T00:25:52","slug":"inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle","status":"publish","type":"post","link":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/","title":{"rendered":"Inicia Gobierno Estatal programa \u201cNuestras Ra\u00edces\u201d para visibilizar la riqueza cultural de Santa Ana del Valle"},"content":{"rendered":"\n<p>\u2022 La Secretar\u00eda de Interculturalidad, Pueblos y Comunidades Ind\u00edgenas y Afromexicanas inaugur\u00f3 una campa\u00f1a de promoci\u00f3n y difusi\u00f3n de las artesan\u00edas de Santa Ana Del Valle<\/p>\n\n\n\n<p>Oaxaca de Ju\u00e1rez, Oax., 10 de febrero de 2023.- El Gobierno del Estado, por conducto de diversas dependencias inaugur\u00f3 el Programa \u201cNuestras ra\u00edces\u201d, la esencia de las culturas, el cual tiene como prop\u00f3sito difundir el origen de los pueblos, comunidades ind\u00edgenas y afromexicanas.<\/p>\n\n\n\n<p>Esta actividad abona a la Interculturalidad, el cual es uno de los ejes de gobierno que ha instruido el Gobernador del Estado, Salom\u00f3n Jara Cruz, para poder lograr en la entidad la verdadera transformaci\u00f3n que el Estado necesita.<\/p>\n\n\n\n<p>Por ello, la ma\u00f1ana de este viernes Berta Ruth Arreola Ruiz, titular de la Secretar\u00eda de Interculturalidad, Pueblos y Comunidades Ind\u00edgenas y Afromexicanas, indic\u00f3 que, por instrucci\u00f3n del Gobernador, Salom\u00f3n Jara Cruz, este programa tiene como objetivo restituir la deuda hist\u00f3rica que se ha tenido durante muchos a\u00f1os con los pueblos ind\u00edgenas de la entidad.<\/p>\n\n\n\n<p>Tambi\u00e9n, se\u00f1al\u00f3 que esta iniciativa alcanzar\u00e1 m\u00e1s municipios, para que de forma conjunta con la Secretar\u00eda de Turismo, puedan coadyuvar esfuerzos y realizar un excelente trabajo de promoci\u00f3n.<\/p>\n\n\n\n<p>Tambi\u00e9n, asistieron Saymi Pineda Velasco, Titular de la Secretar\u00eda de Turismo, representantes de la Secretaria de Bienestar, Tequio e Inclusi\u00f3n, la Secretar\u00eda de Desarrollo Econ\u00f3mico y autoridades municipales, quienes dieron inicio a esta iniciativa que pretende visibilizar el valioso trabajo de las y los artesanos oaxaque\u00f1os.<\/p>\n\n\n\n<p>En un recorrido por las calles de la comunidad, las y los habitantes dieron una muestra de la riqueza cultural del lugar, as\u00ed como los procesos del tejido de sus textiles t\u00edpicos.<\/p>\n\n\n\n<p>As\u00ed mismo, manifestaron su agradecimiento al Gobierno Estatal por voltear la mirada hacia su talento, el cual, durante las anteriores administraciones, fue olvidado.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0154-1024x683.jpg\" alt=\"\" data-id=\"5979\" data-full-url=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0154.jpg\" data-link=\"https:\/\/publimar.mx\/?attachment_id=5979\" class=\"wp-image-5979\" srcset=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0154-1024x683.jpg 1024w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0154-300x200.jpg 300w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0154-768x512.jpg 768w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0154.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0155-1024x683.jpg\" alt=\"\" data-id=\"5980\" data-full-url=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0155.jpg\" data-link=\"https:\/\/publimar.mx\/?attachment_id=5980\" class=\"wp-image-5980\" srcset=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0155-1024x683.jpg 1024w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0155-300x200.jpg 300w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0155-768x512.jpg 768w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0155.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0156-1024x683.jpg\" alt=\"\" data-id=\"5981\" data-full-url=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0156.jpg\" data-link=\"https:\/\/publimar.mx\/?attachment_id=5981\" class=\"wp-image-5981\" srcset=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0156-1024x683.jpg 1024w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0156-300x200.jpg 300w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0156-768x512.jpg 768w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0156.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0157-1024x683.jpg\" alt=\"\" data-id=\"5982\" data-full-url=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0157.jpg\" data-link=\"https:\/\/publimar.mx\/?attachment_id=5982\" class=\"wp-image-5982\" srcset=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0157-1024x683.jpg 1024w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0157-300x200.jpg 300w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0157-768x512.jpg 768w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0157.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0158-1024x683.jpg\" alt=\"\" data-id=\"5983\" data-full-url=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0158.jpg\" data-link=\"https:\/\/publimar.mx\/?attachment_id=5983\" class=\"wp-image-5983\" srcset=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0158-1024x683.jpg 1024w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0158-300x200.jpg 300w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0158-768x512.jpg 768w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0158.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 La Secretar\u00eda de Interculturalidad, Pueblos y Comunidades Ind\u00edgenas y Afromexicanas inaugur\u00f3 una campa\u00f1a de promoci\u00f3n y difusi\u00f3n de las artesan\u00edas de Santa Ana Del Valle Oaxaca de Ju\u00e1rez, Oax.,&hellip; <\/p>\n","protected":false},"author":1,"featured_media":5979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[3,14,19],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inicia Gobierno Estatal programa \u201cNuestras Ra\u00edces\u201d para visibilizar la riqueza cultural de Santa Ana del Valle - PubliMar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inicia Gobierno Estatal programa \u201cNuestras Ra\u00edces\u201d para visibilizar la riqueza cultural de Santa Ana del Valle - PubliMar\" \/>\n<meta property=\"og:description\" content=\"\u2022 La Secretar\u00eda de Interculturalidad, Pueblos y Comunidades Ind\u00edgenas y Afromexicanas inaugur\u00f3 una campa\u00f1a de promoci\u00f3n y difusi\u00f3n de las artesan\u00edas de Santa Ana Del Valle Oaxaca de Ju\u00e1rez, Oax.,&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/\" \/>\n<meta property=\"og:site_name\" content=\"PubliMar\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-11T00:25:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-11T00:25:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0154.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/publimar.mx\/#website\",\"url\":\"https:\/\/publimar.mx\/\",\"name\":\"PubliMar\",\"description\":\"Informaci\\u00f3n de la Costa Oaxaque\\u00f1a\",\"publisher\":{\"@id\":\"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/publimar.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0154.jpg\",\"contentUrl\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0154.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#webpage\",\"url\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/\",\"name\":\"Inicia Gobierno Estatal programa \\u201cNuestras Ra\\u00edces\\u201d para visibilizar la riqueza cultural de Santa Ana del Valle - PubliMar\",\"isPartOf\":{\"@id\":\"https:\/\/publimar.mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#primaryimage\"},\"datePublished\":\"2023-02-11T00:25:50+00:00\",\"dateModified\":\"2023-02-11T00:25:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/publimar.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inicia Gobierno Estatal programa \\u201cNuestras Ra\\u00edces\\u201d para visibilizar la riqueza cultural de Santa Ana del Valle\"}]},{\"@type\":[\"Article\",\"NewsArticle\"],\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#webpage\"},\"author\":{\"@id\":\"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558\"},\"headline\":\"Inicia Gobierno Estatal programa \\u201cNuestras Ra\\u00edces\\u201d para visibilizar la riqueza cultural de Santa Ana del Valle\",\"datePublished\":\"2023-02-11T00:25:50+00:00\",\"dateModified\":\"2023-02-11T00:25:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#webpage\"},\"wordCount\":338,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558\"},\"image\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0154.jpg\",\"articleSection\":[\"cultura\",\"Regional\",\"Turismo..\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#respond\"]}]},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/publimar.mx\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png\",\"contentUrl\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png\",\"width\":454,\"height\":108,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/publimar.mx\/#personlogo\"},\"sameAs\":[\"https:\/\/publimar.mx\"],\"url\":\"https:\/\/publimar.mx\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inicia Gobierno Estatal programa \u201cNuestras Ra\u00edces\u201d para visibilizar la riqueza cultural de Santa Ana del Valle - PubliMar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/","og_locale":"es_ES","og_type":"article","og_title":"Inicia Gobierno Estatal programa \u201cNuestras Ra\u00edces\u201d para visibilizar la riqueza cultural de Santa Ana del Valle - PubliMar","og_description":"\u2022 La Secretar\u00eda de Interculturalidad, Pueblos y Comunidades Ind\u00edgenas y Afromexicanas inaugur\u00f3 una campa\u00f1a de promoci\u00f3n y difusi\u00f3n de las artesan\u00edas de Santa Ana Del Valle Oaxaca de Ju\u00e1rez, Oax.,&hellip;","og_url":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/","og_site_name":"PubliMar","article_published_time":"2023-02-11T00:25:50+00:00","article_modified_time":"2023-02-11T00:25:52+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0154.jpg","path":"\/home\/u358712125\/domains\/publimar.mx\/public_html\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0154.jpg","size":"full","id":5979,"alt":"","pixels":1093120,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/publimar.mx\/#website","url":"https:\/\/publimar.mx\/","name":"PubliMar","description":"Informaci\u00f3n de la Costa Oaxaque\u00f1a","publisher":{"@id":"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/publimar.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#primaryimage","inLanguage":"es","url":"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0154.jpg","contentUrl":"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0154.jpg","width":1280,"height":854},{"@type":"WebPage","@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#webpage","url":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/","name":"Inicia Gobierno Estatal programa \u201cNuestras Ra\u00edces\u201d para visibilizar la riqueza cultural de Santa Ana del Valle - PubliMar","isPartOf":{"@id":"https:\/\/publimar.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#primaryimage"},"datePublished":"2023-02-11T00:25:50+00:00","dateModified":"2023-02-11T00:25:52+00:00","breadcrumb":{"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/publimar.mx\/"},{"@type":"ListItem","position":2,"name":"Inicia Gobierno Estatal programa \u201cNuestras Ra\u00edces\u201d para visibilizar la riqueza cultural de Santa Ana del Valle"}]},{"@type":["Article","NewsArticle"],"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#article","isPartOf":{"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#webpage"},"author":{"@id":"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558"},"headline":"Inicia Gobierno Estatal programa \u201cNuestras Ra\u00edces\u201d para visibilizar la riqueza cultural de Santa Ana del Valle","datePublished":"2023-02-11T00:25:50+00:00","dateModified":"2023-02-11T00:25:52+00:00","mainEntityOfPage":{"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#webpage"},"wordCount":338,"commentCount":0,"publisher":{"@id":"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558"},"image":{"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#primaryimage"},"thumbnailUrl":"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0154.jpg","articleSection":["cultura","Regional","Turismo.."],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/publimar.mx\/index.php\/2023\/02\/10\/inicia-gobierno-estatal-programa-nuestras-raices-para-visibilizar-la-riqueza-cultural-de-santa-ana-del-valle\/#respond"]}]},{"@type":["Person","Organization"],"@id":"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/publimar.mx\/#personlogo","inLanguage":"es","url":"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png","contentUrl":"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png","width":454,"height":108,"caption":"admin"},"logo":{"@id":"https:\/\/publimar.mx\/#personlogo"},"sameAs":["https:\/\/publimar.mx"],"url":"https:\/\/publimar.mx\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/posts\/5978"}],"collection":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5978"}],"version-history":[{"count":2,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/posts\/5978\/revisions"}],"predecessor-version":[{"id":5985,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/posts\/5978\/revisions\/5985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/media\/5979"}],"wp:attachment":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}