{"id":5964,"date":"2023-02-10T13:33:25","date_gmt":"2023-02-10T19:33:25","guid":{"rendered":"https:\/\/publimar.mx\/?p=5964"},"modified":"2023-02-10T13:34:31","modified_gmt":"2023-02-10T19:34:31","slug":"en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades","status":"publish","type":"post","link":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/","title":{"rendered":"En Asamblea Comunitaria, Candelaria Loxicha decidir\u00e1 si hay o no elecci\u00f3n consecutiva o reelecci\u00f3n de autoridades"},"content":{"rendered":"\n<ul><li>Sin invitar a ex autoridades, aspirantes a la presidencia acuerdan con personal del IEEPC, SEGO y Comisi\u00f3n Municipal, la realizaci\u00f3n de Asamblea Comunitaria<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"460\" src=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0058-1024x460.jpg\" alt=\"\" class=\"wp-image-5966\" srcset=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0058-1024x460.jpg 1024w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0058-300x135.jpg 300w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0058-768x345.jpg 768w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0058-1536x690.jpg 1536w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0058.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Ra\u00fal Laguna<\/p>\n\n\n\n<p>En medio de amenazas hacia el comisionado municipal provisional de Candelaria Loxicha y como parte del cumplimiento a una sentencia emitida por la Sala Regional Xalapa del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n, el pr\u00f3ximo domingo 12 de febrero se realizar\u00e1 una Asamblea comunitaria en \u00e9ste municipio donde habitantes definir\u00e1n si aceptan o no la reelecci\u00f3n o elecci\u00f3n consecutiva de sus autoridades.<\/p>\n\n\n\n<p>A unos d\u00edas de la llegada de Alexis Carballo Fuentevilla como Comisionado Municipal Provisional en \u00e9sta municipalidad, debido a la falta de acuerdos para celebrar, el a\u00f1o pasado, elecci\u00f3n a presidente municipal bajo el Sistema Normativos Ind\u00edgenas o conocidos como \u201cUsos y Costumbres\u201d; ahora aspirantes a ocupar la presidencia, autoridades municipales y del Instituto Estatal Electoral y de Participaci\u00f3n Ciudadana de Oaxaca (IEEPCO), trazan la ruta para llevar a cabo la elecci\u00f3n municipal y elegir a las nuevas autoridades.<\/p>\n\n\n\n<p>A \u00e9sta minuta de Trabajo no fueron invitados las ex autoridades municipales; sobre todo al ex presidente municipal quien pretende ser tomado en cuenta como candidato a una elecci\u00f3n consecutiva.<\/p>\n\n\n\n<p>Como primer punto tienen que dar cumplimiento a una sentencia emitida por la Sala Regional Xalapa, sobre la celebraci\u00f3n de la Asamblea Comunitaria y se tendr\u00e1 que someter a la Asamblea para que se pronuncie sobre la implementaci\u00f3n o no de la elecci\u00f3n consecutiva o reelecci\u00f3n de sus autoridades municipales.<\/p>\n\n\n\n<p>En la Minuta de Trabajo participan aspirantes a la presidencia municipal<\/p>\n\n\n\n<p>Ante la Direcci\u00f3n Ejecutiva de Sistemas Normativos Ind\u00edgenas del IEEPCO y el personal de la Secretar\u00eda de Gobierno del estado de Oaxaca, los participantes, el comisionado Municipal Provisional de Candelaria Loxicha, Alexis Carballo Fuentevilla; agentes municipales; as\u00ed como integrantes del Consejo Municipal Electoral y ciudadanos de dicha poblaci\u00f3n, entre los que destacan aspirantes a la presidencia municipal, como Felipe Reyes Santiago, Rom\u00e1n Ruiz Boh\u00f3rquez y Efra\u00edn Valencia Hern\u00e1ndez, firmaron una minuta de trabajo en la que acordaron la emisi\u00f3n de una convocatoria para celebrar la Asamblea Comunitaria.<\/p>\n\n\n\n<p>Los aspirantes a la presidencia municipal, insisten en que en la pr\u00f3xima elecci\u00f3n no participe el ex presidente municipal de Candelaria Loxicha, Gabriel Hern\u00e1ndez Garc\u00eda, por lo que exigen al IEEPCO y al Comisionado Municipal en la realizaci\u00f3n de la Asamblea Comunitaria que hace unos meses, la Sala Xalapa del Tribunal Electoral de la Federaci\u00f3n exigiera mediante una sentencia emitida.<\/p>\n\n\n\n<p>Comisionado recibe amenazas por parte de familiar de candidato<\/p>\n\n\n\n<p>Entre lo expuestos por los participantes y se asienta en la Minuta de Trabajo, son las amenazas que ha recibido el Comisionado Municipal, Alexis Carballo por parte de un ciudadano de Candelaria Loxicha, a quien refiere con el nombre de Miguel \u00c1ngel Valencia, quien \u201cme ha marcado y amenazado y quien le he permitido opinar, siento que es interesado directamente me ha estado pidiendo trabajo\u201d, se manifiesta en la minuta de trabajo.<\/p>\n\n\n\n<p>Otro de los participantes, Ismael Mendoza Cortez manifest\u00f3 \u201cque la ley se encargue, no queremos pretexto, el compa\u00f1ero que est\u00e1 aqu\u00ed es su hermano (refiri\u00e9ndose a Efra\u00edn Valencia Hern\u00e1ndez), yo le pedir\u00eda que hablara con \u00e9l para que no haya problemas\u201d, emiti\u00f3.<\/p>\n\n\n\n<p>En su participaci\u00f3n, Efra\u00edn Valencia Hern\u00e1ndez, aspirante a presidente municipal de Candelaria Loxicha acept\u00f3 ser hermano de Miguel \u00c1ngel Valencia y dijo que le enviar\u00eda mensaje, \u201cyo lo que quiero es que ya salga la elecci\u00f3n, no todos somos iguales, de mi parte yo hablar\u00e9 con mi hermano, tenga por seguro que no va a suceder\u201d, se refiri\u00f3 hacia el Comisionado Municipal, quien pidi\u00f3 se garantizara su seguridad.<\/p>\n\n\n\n<p>Comisionado exige seguridad a su persona<\/p>\n\n\n\n<p>Alexis Carballo Fuentevilla pidi\u00f3 se garantice la seguridad; sobre todo su integridad f\u00edsica debido a las amenazas de ser violentado por parte de un ciudadano de Candelaria Loxicha, con la finalidad de llevar a cabo la Asamblea Comunitaria que piden los participantes en dicha reuni\u00f3n.<\/p>\n\n\n\n<p>Por su parte, el funcionario electoral, Salvador Isidro S\u00e1nchez Pablo manifest\u00f3 que el IEEPCO les brindar\u00e1 la seguridad al solicitar el auxilio de la Fuerza P\u00fablica para el d\u00eda de la Asamblea<\/p>\n\n\n\n<p>La Asamblea Comunitaria se realizar\u00e1 pr\u00f3ximo domingo<\/p>\n\n\n\n<p>Para la celebraci\u00f3n de la Asamblea Comunitaria, los participantes en la Minuta de Trabajo acordaron que se llevar\u00e1 a cabo el pr\u00f3ximo domingo 12 de febrero; se instalar\u00e1n cinco mesas de registro para la cabecera municipal y cinco mesas para cada una de las Agencias Municipales y de Polic\u00edas.<\/p>\n\n\n\n<p>En las mesas de registro que se instalar\u00e1n desde las ocho a once de la ma\u00f1ana del domingo 12 de febrero, estar\u00e1n ciudadanos nombrados por sus agentes municipales para que auxilien los registros de asistencia.<\/p>\n\n\n\n<p>La Asamblea Comunitaria dar\u00e1 inicio a las 11:00 de la ma\u00f1ana, siempre y cuando exista un Quorum legal que ser\u00e1 verificado por el Comisionado Municipal.<\/p>\n\n\n\n<p>El quorum legal se tomar\u00e1 en consideraci\u00f3n a la asistencia de asambleas comunitarias anteriores, las que han oscilado en cuatro mil ciudadanos; lo que dar\u00e1 referencia para un qu\u00f3rum legal de 2 mil m\u00e1s un ciudadanos para que se pueda instalar la Asamblea.<\/p>\n\n\n\n<p>Para poder ser asistente a la Asamblea, un ciudadano debe contar con su credencial de Elector que presentar\u00e1 en la Mesa correspondiente a su agencia municipal.<\/p>\n\n\n\n<p>Pronunciaci\u00f3n a la implementaci\u00f3n o no de una elecci\u00f3n Consecutiva<\/p>\n\n\n\n<p>Ser\u00e1 el Comisionado quien someter\u00e1 a la Asamblea el nombramiento de los integrantes de la Mesa de los Debates; as\u00ed mismo informar\u00e1 sobre la sentencia emitida por el Tribunal Federal y el contenido de los acuerdos del IEEPCO.<\/p>\n\n\n\n<p>Ser\u00e1 el Comisionado Municipal quien someter\u00e1 a la Asamblea para que se pronuncie sobre la implementaci\u00f3n o no de la elecci\u00f3n consecutiva o reelecci\u00f3n de sus autoridades municipales en el Sistema Normativo Interno de Candelaria Loxicha.<\/p>\n\n\n\n<p>La forma de elecci\u00f3n en \u00e9sta Asamblea Comunitaria ser\u00e1 a mano alzada atendiendo a su uso y costumbre de la poblaci\u00f3n<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"461\" src=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0059-1024x461.jpg\" alt=\"\" class=\"wp-image-5965\" srcset=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0059-1024x461.jpg 1024w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0059-300x135.jpg 300w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0059-768x346.jpg 768w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0059-1536x692.jpg 1536w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0059.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"461\" src=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0060-1024x461.jpg\" alt=\"\" class=\"wp-image-5967\" srcset=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0060-1024x461.jpg 1024w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0060-300x135.jpg 300w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0060-768x346.jpg 768w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0060-1536x692.jpg 1536w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0060.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"460\" src=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0061-1024x460.jpg\" alt=\"\" class=\"wp-image-5968\" srcset=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0061-1024x460.jpg 1024w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0061-300x135.jpg 300w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0061-768x345.jpg 768w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0061-1536x690.jpg 1536w, https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0061.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Sin invitar a ex autoridades, aspirantes a la presidencia acuerdan con personal del IEEPC, SEGO y Comisi\u00f3n Municipal, la realizaci\u00f3n de Asamblea Comunitaria Ra\u00fal Laguna En medio de amenazas hacia&hellip; <\/p>\n","protected":false},"author":1,"featured_media":5966,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[13,15],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En Asamblea Comunitaria, Candelaria Loxicha decidir\u00e1 si hay o no elecci\u00f3n consecutiva o reelecci\u00f3n de autoridades - PubliMar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Asamblea Comunitaria, Candelaria Loxicha decidir\u00e1 si hay o no elecci\u00f3n consecutiva o reelecci\u00f3n de autoridades - PubliMar\" \/>\n<meta property=\"og:description\" content=\"Sin invitar a ex autoridades, aspirantes a la presidencia acuerdan con personal del IEEPC, SEGO y Comisi\u00f3n Municipal, la realizaci\u00f3n de Asamblea Comunitaria Ra\u00fal Laguna En medio de amenazas hacia&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/\" \/>\n<meta property=\"og:site_name\" content=\"PubliMar\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-10T19:33:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-10T19:34:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0058.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"719\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/publimar.mx\/#website\",\"url\":\"https:\/\/publimar.mx\/\",\"name\":\"PubliMar\",\"description\":\"Informaci\\u00f3n de la Costa Oaxaque\\u00f1a\",\"publisher\":{\"@id\":\"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/publimar.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0058.jpg\",\"contentUrl\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0058.jpg\",\"width\":1600,\"height\":719},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#webpage\",\"url\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/\",\"name\":\"En Asamblea Comunitaria, Candelaria Loxicha decidir\\u00e1 si hay o no elecci\\u00f3n consecutiva o reelecci\\u00f3n de autoridades - PubliMar\",\"isPartOf\":{\"@id\":\"https:\/\/publimar.mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#primaryimage\"},\"datePublished\":\"2023-02-10T19:33:25+00:00\",\"dateModified\":\"2023-02-10T19:34:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/publimar.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Asamblea Comunitaria, Candelaria Loxicha decidir\\u00e1 si hay o no elecci\\u00f3n consecutiva o reelecci\\u00f3n de autoridades\"}]},{\"@type\":[\"Article\",\"NewsArticle\"],\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#webpage\"},\"author\":{\"@id\":\"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558\"},\"headline\":\"En Asamblea Comunitaria, Candelaria Loxicha decidir\\u00e1 si hay o no elecci\\u00f3n consecutiva o reelecci\\u00f3n de autoridades\",\"datePublished\":\"2023-02-10T19:33:25+00:00\",\"dateModified\":\"2023-02-10T19:34:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#webpage\"},\"wordCount\":1052,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558\"},\"image\":{\"@id\":\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0058.jpg\",\"articleSection\":[\"Pol\\u00edtica\",\"Regional.\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#respond\"]}]},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/publimar.mx\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png\",\"contentUrl\":\"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png\",\"width\":454,\"height\":108,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/publimar.mx\/#personlogo\"},\"sameAs\":[\"https:\/\/publimar.mx\"],\"url\":\"https:\/\/publimar.mx\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Asamblea Comunitaria, Candelaria Loxicha decidir\u00e1 si hay o no elecci\u00f3n consecutiva o reelecci\u00f3n de autoridades - PubliMar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/","og_locale":"es_ES","og_type":"article","og_title":"En Asamblea Comunitaria, Candelaria Loxicha decidir\u00e1 si hay o no elecci\u00f3n consecutiva o reelecci\u00f3n de autoridades - PubliMar","og_description":"Sin invitar a ex autoridades, aspirantes a la presidencia acuerdan con personal del IEEPC, SEGO y Comisi\u00f3n Municipal, la realizaci\u00f3n de Asamblea Comunitaria Ra\u00fal Laguna En medio de amenazas hacia&hellip;","og_url":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/","og_site_name":"PubliMar","article_published_time":"2023-02-10T19:33:25+00:00","article_modified_time":"2023-02-10T19:34:31+00:00","og_image":[{"width":1600,"height":719,"url":"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0058.jpg","path":"\/home\/u358712125\/domains\/publimar.mx\/public_html\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0058.jpg","size":"full","id":5966,"alt":"","pixels":1150400,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/publimar.mx\/#website","url":"https:\/\/publimar.mx\/","name":"PubliMar","description":"Informaci\u00f3n de la Costa Oaxaque\u00f1a","publisher":{"@id":"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/publimar.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#primaryimage","inLanguage":"es","url":"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0058.jpg","contentUrl":"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0058.jpg","width":1600,"height":719},{"@type":"WebPage","@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#webpage","url":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/","name":"En Asamblea Comunitaria, Candelaria Loxicha decidir\u00e1 si hay o no elecci\u00f3n consecutiva o reelecci\u00f3n de autoridades - PubliMar","isPartOf":{"@id":"https:\/\/publimar.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#primaryimage"},"datePublished":"2023-02-10T19:33:25+00:00","dateModified":"2023-02-10T19:34:31+00:00","breadcrumb":{"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/publimar.mx\/"},{"@type":"ListItem","position":2,"name":"En Asamblea Comunitaria, Candelaria Loxicha decidir\u00e1 si hay o no elecci\u00f3n consecutiva o reelecci\u00f3n de autoridades"}]},{"@type":["Article","NewsArticle"],"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#article","isPartOf":{"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#webpage"},"author":{"@id":"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558"},"headline":"En Asamblea Comunitaria, Candelaria Loxicha decidir\u00e1 si hay o no elecci\u00f3n consecutiva o reelecci\u00f3n de autoridades","datePublished":"2023-02-10T19:33:25+00:00","dateModified":"2023-02-10T19:34:31+00:00","mainEntityOfPage":{"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#webpage"},"wordCount":1052,"commentCount":0,"publisher":{"@id":"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558"},"image":{"@id":"https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#primaryimage"},"thumbnailUrl":"https:\/\/publimar.mx\/wp-content\/uploads\/2023\/02\/IMG-20230210-WA0058.jpg","articleSection":["Pol\u00edtica","Regional."],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/publimar.mx\/index.php\/2023\/02\/10\/en-asamblea-comunitaria-candelaria-loxicha-decidira-si-hay-o-no-eleccion-consecutiva-o-reeleccion-de-autoridades\/#respond"]}]},{"@type":["Person","Organization"],"@id":"https:\/\/publimar.mx\/#\/schema\/person\/42ad4d315580276616a11863a241f558","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/publimar.mx\/#personlogo","inLanguage":"es","url":"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png","contentUrl":"https:\/\/publimar.mx\/wp-content\/uploads\/2021\/08\/logo.png","width":454,"height":108,"caption":"admin"},"logo":{"@id":"https:\/\/publimar.mx\/#personlogo"},"sameAs":["https:\/\/publimar.mx"],"url":"https:\/\/publimar.mx\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/posts\/5964"}],"collection":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5964"}],"version-history":[{"count":2,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/posts\/5964\/revisions"}],"predecessor-version":[{"id":5970,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/posts\/5964\/revisions\/5970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/media\/5966"}],"wp:attachment":[{"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/publimar.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}